{"id":88033,"date":"2024-06-03T04:32:28","date_gmt":"2024-06-03T04:32:28","guid":{"rendered":"https:\/\/switch-electric.eu\/?post_type=product&#038;p=88033"},"modified":"2024-06-03T04:32:28","modified_gmt":"2024-06-03T04:32:28","slug":"base-diazed-1p-diii-e33-63a-sc-p85mm-2","status":"publish","type":"product","link":"https:\/\/switch-electric.eu\/fi\/product\/base-diazed-1p-diii-e33-63a-sc-p85mm-2\/","title":{"rendered":"BASE DIAZED 1P DIII E33 63A SC P=85mm"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":19962,"template":"","meta":[],"product_cat":[193],"product_tag":[],"class_list":{"0":"post-88033","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-siemens","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/88033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/88033\/revisions"}],"predecessor-version":[{"id":88034,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/88033\/revisions\/88034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/media\/19962"}],"wp:attachment":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/media?parent=88033"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product_cat?post=88033"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product_tag?post=88033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}