{"id":42155,"date":"2024-06-02T23:18:38","date_gmt":"2024-06-02T23:18:38","guid":{"rendered":"https:\/\/switch-electric.eu\/?post_type=product&#038;p=42155"},"modified":"2024-06-02T23:18:39","modified_gmt":"2024-06-02T23:18:39","slug":"conts2-185kw-208v-50-60hz","status":"publish","type":"product","link":"https:\/\/switch-electric.eu\/fi\/product\/conts2-185kw-208v-50-60hz\/","title":{"rendered":"CONTS2 18,5KW 208V 50-60HZ"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":19962,"template":"","meta":[],"product_cat":[193],"product_tag":[],"class_list":["post-42155","product","type-product","status-publish","has-post-thumbnail","product_cat-siemens","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/42155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/42155\/revisions"}],"predecessor-version":[{"id":42156,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/42155\/revisions\/42156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/media\/19962"}],"wp:attachment":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/media?parent=42155"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product_cat?post=42155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product_tag?post=42155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}