{"id":128066,"date":"2024-06-03T07:46:07","date_gmt":"2024-06-03T07:46:07","guid":{"rendered":"https:\/\/switch-electric.eu\/?post_type=product&#038;p=128066"},"modified":"2024-06-03T07:46:07","modified_gmt":"2024-06-03T07:46:07","slug":"tv-single-shield-female-passage-socket-2","status":"publish","type":"product","link":"https:\/\/switch-electric.eu\/fi\/product\/tv-single-shield-female-passage-socket-2\/","title":{"rendered":"TV single shield female passage socket"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":19947,"template":"","meta":[],"product_cat":[197],"product_tag":[],"class_list":{"0":"post-128066","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-schneider","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/128066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/128066\/revisions"}],"predecessor-version":[{"id":128067,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product\/128066\/revisions\/128067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/media\/19947"}],"wp:attachment":[{"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/media?parent=128066"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product_cat?post=128066"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/switch-electric.eu\/fi\/wp-json\/wp\/v2\/product_tag?post=128066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}